{"id":2660,"date":"2025-02-04T21:46:24","date_gmt":"2025-02-04T20:46:24","guid":{"rendered":"http:\/\/golvet.de\/?page_id=2660"},"modified":"2026-06-04T12:37:21","modified_gmt":"2026-06-04T10:37:21","slug":"menu","status":"publish","type":"page","link":"https:\/\/golvet.de\/en\/menu\/","title":{"rendered":"Menu"},"content":{"rendered":"\n<h1>\n\t\t\tHerzlich Willkommen &#8211; hier sind Sie richtig!\t<\/h1>\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/golvet.de\/wp-content\/uploads\/2026\/06\/Menue-GOLVET-Juni_Seite_2.png\" alt=\"Men\u00fc GOLVET Juni_Seite_2\" itemprop=\"image\" title=\"Men\u00fc GOLVET Juni_Seite_2\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t\t<img decoding=\"async\" src=\"http:\/\/golvet.de\/wp-content\/uploads\/2026\/06\/Menue-GOLVET-Juni_Seite_4.png\" alt=\"Men\u00fc GOLVET Juni_Seite_4\" itemprop=\"image\" title=\"Men\u00fc GOLVET Juni_Seite_4\" onerror=\"this.style.display='none'\" loading=\"lazy\" \/>\n\t\t\t<a href=\"http:\/\/golvet.de\/wp-content\/uploads\/2025\/05\/Weinkarte-Neue-Erste-Version-2025-3feb.pdf\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\tWine Menu\n\t\t\t\t\t<\/a>\n\t\t\t<a href=\"http:\/\/golvet.de\/wp-content\/uploads\/2026\/01\/Bar-Menu-Golvet_PMS_Mar2026.pdf\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\tBar Menu\n\t\t\t\t\t<\/a>\n\n","protected":false},"excerpt":{"rendered":"<p>Herzlich Willkommen &#8211; hier sind Sie richtig! Wine Menu Bar Menu<\/p>\n","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2660","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Menu - GOLVET<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/golvet.de\/en\/menu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Menu - GOLVET\" \/>\n<meta property=\"og:description\" content=\"Herzlich Willkommen &#8211; hier sind Sie richtig! Wine Menu Bar Menu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/golvet.de\/en\/menu\/\" \/>\n<meta property=\"og:site_name\" content=\"GOLVET\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T10:37:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/golvet.de\/wp-content\/uploads\/2026\/06\/Menue-GOLVET-Juni_Seite_2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/golvet.de\\\/en\\\/menu\\\/\",\"url\":\"https:\\\/\\\/golvet.de\\\/en\\\/menu\\\/\",\"name\":\"Menu - GOLVET\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golvet.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/golvet.de\\\/en\\\/menu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/golvet.de\\\/en\\\/menu\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/golvet.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Menue-GOLVET-Juni_Seite_2.png\",\"datePublished\":\"2025-02-04T20:46:24+00:00\",\"dateModified\":\"2026-06-04T10:37:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/golvet.de\\\/en\\\/menu\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/golvet.de\\\/en\\\/menu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/golvet.de\\\/en\\\/menu\\\/#primaryimage\",\"url\":\"http:\\\/\\\/golvet.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Menue-GOLVET-Juni_Seite_2.png\",\"contentUrl\":\"http:\\\/\\\/golvet.de\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Menue-GOLVET-Juni_Seite_2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/golvet.de\\\/en\\\/menu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/golvet.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Menu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/golvet.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/golvet.de\\\/en\\\/\",\"name\":\"GOLVET\",\"description\":\"Casual-Fine-Dining und Hauptstadtblick in einzigartiger Atmosph\u00e4re: modern, kreativ, urban, beeindruckend!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/golvet.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Menu - GOLVET","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/golvet.de\/en\/menu\/","og_locale":"en_US","og_type":"article","og_title":"Menu - GOLVET","og_description":"Herzlich Willkommen &#8211; hier sind Sie richtig! Wine Menu Bar Menu","og_url":"https:\/\/golvet.de\/en\/menu\/","og_site_name":"GOLVET","article_modified_time":"2026-06-04T10:37:21+00:00","og_image":[{"url":"http:\/\/golvet.de\/wp-content\/uploads\/2026\/06\/Menue-GOLVET-Juni_Seite_2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/golvet.de\/en\/menu\/","url":"https:\/\/golvet.de\/en\/menu\/","name":"Menu - GOLVET","isPartOf":{"@id":"https:\/\/golvet.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/golvet.de\/en\/menu\/#primaryimage"},"image":{"@id":"https:\/\/golvet.de\/en\/menu\/#primaryimage"},"thumbnailUrl":"http:\/\/golvet.de\/wp-content\/uploads\/2026\/06\/Menue-GOLVET-Juni_Seite_2.png","datePublished":"2025-02-04T20:46:24+00:00","dateModified":"2026-06-04T10:37:21+00:00","breadcrumb":{"@id":"https:\/\/golvet.de\/en\/menu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/golvet.de\/en\/menu\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/golvet.de\/en\/menu\/#primaryimage","url":"http:\/\/golvet.de\/wp-content\/uploads\/2026\/06\/Menue-GOLVET-Juni_Seite_2.png","contentUrl":"http:\/\/golvet.de\/wp-content\/uploads\/2026\/06\/Menue-GOLVET-Juni_Seite_2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/golvet.de\/en\/menu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/golvet.de\/en\/"},{"@type":"ListItem","position":2,"name":"Menu"}]},{"@type":"WebSite","@id":"https:\/\/golvet.de\/en\/#website","url":"https:\/\/golvet.de\/en\/","name":"GOLVET","description":"Casual-Fine-Dining und Hauptstadtblick in einzigartiger Atmosph\u00e4re: modern, kreativ, urban, beeindruckend!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/golvet.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"a.schermall","author_link":"https:\/\/golvet.de\/en\/author\/a-schermall\/"},"uagb_comment_info":0,"uagb_excerpt":"Herzlich Willkommen &#8211; hier sind Sie richtig! Wine Menu Bar Menu","_links":{"self":[{"href":"https:\/\/golvet.de\/en\/wp-json\/wp\/v2\/pages\/2660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golvet.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/golvet.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/golvet.de\/en\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/golvet.de\/en\/wp-json\/wp\/v2\/comments?post=2660"}],"version-history":[{"count":2,"href":"https:\/\/golvet.de\/en\/wp-json\/wp\/v2\/pages\/2660\/revisions"}],"predecessor-version":[{"id":4006,"href":"https:\/\/golvet.de\/en\/wp-json\/wp\/v2\/pages\/2660\/revisions\/4006"}],"wp:attachment":[{"href":"https:\/\/golvet.de\/en\/wp-json\/wp\/v2\/media?parent=2660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}